{"id":4376,"date":"2015-06-22T08:55:07","date_gmt":"2015-06-22T08:55:07","guid":{"rendered":"https:\/\/vila.es\/de\/?p=1794"},"modified":"2021-02-17T11:39:21","modified_gmt":"2021-02-17T11:39:21","slug":"ist-gemuse-patentierbar","status":"publish","type":"post","link":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/","title":{"rendered":"IST GEM\u00dcSE PATENTIERBAR?"},"content":{"rendered":"<p style=\"text-align: justify;\">Die j\u00fcngsten Entscheidungen G2\/12 und G2\/13 der Gro\u00dfen Beschwerdekammer des Europ\u00e4ischen Patentamts (\u201eEP\u201c), vom 25. M\u00e4rz 2015, sind nicht ohne Polemik empfangen worden.<\/p>\n<p style=\"text-align: justify;\">Beide best\u00e4tigen, dass Erzeugnispatente auf Pflanzen und Pflanzenmaterial erteilt werden k\u00f6nnen, was im Prinzip dem Verbot des Artikels 53 (b), welches a priori biologische Verfahren zur Z\u00fcchtung von Pflanzen oder Tieren der Patentierbarkeit ausschlie\u00dft, widersprechen k\u00f6nnte. Das EP erkl\u00e4rt, dass dieser Artikel in dem Sinne auszulegen ist, dass die Ausnahme der Patentierbarkeit nicht Pflanzen und Teilen davon betrifft (einschlie\u00dflich deren Fr\u00fcchte) welche als Resultat dieser Verfahren entstanden worden sind, sondern allein auf das Verfahren zur Herstellung von, beispielsweise, Brokkoli und Tomaten, so wie im konkreten Fall beschrieben, ausgerichtet ist.<\/p>\n<p style=\"text-align: justify;\">Diese Entscheidungen sind mit erheblichen Kritiken von mehreren internationalen Verb\u00e4nden empfangen worden, haupts\u00e4chlich auf der Grundlage von moralischen sowie von wirtschaftlichen und sozialen Vorw\u00fcrfen. Die Organisation \u201eNo Patent for Seeds\u201c berichtete, dass diese Entscheidung den Weg f\u00fcr die Kontrolle von wichtigen Ressourcen f\u00fcr das Alltagsleben f\u00fcr einzelne Unternehmen vorbereitet. Beispielsweise w\u00fcrde dies eine unerw\u00fcnschte Marktkontrolle herbeif\u00fchren, was Kleinbauer zu sehr von Konzernen abh\u00e4ngig machen und zugleich zum Nachteil der Verbraucher gehen w\u00fcrde. Dadurch wird ersichtlich, dass die Polemik nicht im Rahmen einer juristischen Debatte verl\u00e4uft, sondern eher in Bezug auf konkrete Gesetzespolitik.<\/p>\n<p style=\"text-align: justify;\">Daher sind Brokkoli und Tomaten allein eine Vorspeise von dem, was noch bevorsteht. Die Biotechnologie sowohl im Bereich der Pflanzenz\u00fcchtung sowie auch von medizinischen Verfahren ist ein wesentlicher Teil der Gesellschaft der Zukunft. Um entsprechende Investitionen durchnehmen zu k\u00f6nnen, brauchen die konkreten Gesellschaften vom Staat zuerst eine Garantie der Exklusivit\u00e4t mittels Patente und anderen gewerblichen Schutzrechten. Der Staat, hingegen, muss einen geeigneten Ausgleich finden, um das Gemeinwohl zu sch\u00fctzen, da dadurch genauso viel gewonnen wie verloren werden kann.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Vil\u00e1 Abogados<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">F\u00fcr weitere Informationen, kontaktieren Sie bitte:<\/p>\n<p style=\"text-align: justify;\"><a href=\"mailto:va@vila.es\"><span style=\"color: #3366ff;\">va@vila.es<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">22. Juni 2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die j\u00fcngsten Entscheidungen G2\/12 und G2\/13 der Gro\u00dfen Beschwerdekammer des Europ\u00e4ischen Patentamts (\u201eEP\u201c), vom 25. M\u00e4rz 2015, sind nicht ohne Polemik empfangen worden. Beide best\u00e4tigen, dass Erzeugnispatente auf Pflanzen und Pflanzenmaterial erteilt werden k\u00f6nnen, was im Prinzip dem Verbot des Artikels 53 (b), welches a priori biologische Verfahren zur Z\u00fcchtung von Pflanzen oder Tieren der  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":4723,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[],"class_list":["post-4376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urheberrecht-und-gewerbliches-eigentum"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IST GEM\u00dcSE PATENTIERBAR?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IST GEM\u00dcSE PATENTIERBAR?\" \/>\n<meta property=\"og:description\" content=\"Die j\u00fcngsten Entscheidungen G2\/12 und G2\/13 der Gro\u00dfen Beschwerdekammer des Europ\u00e4ischen Patentamts (\u201eEP\u201c), vom 25. M\u00e4rz 2015, sind nicht ohne Polemik empfangen worden. Beide best\u00e4tigen, dass Erzeugnispatente auf Pflanzen und Pflanzenmaterial erteilt werden k\u00f6nnen, was im Prinzip dem Verbot des Artikels 53 (b), welches a priori biologische Verfahren zur Z\u00fcchtung von Pflanzen oder Tieren der [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/\" \/>\n<meta property=\"og:site_name\" content=\"Vil\u00e1 Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-22T08:55:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-17T11:39:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"669\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vil\u00e1 Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vil\u00e1 Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/\"},\"author\":{\"name\":\"Vil\u00e1 Abogados\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"headline\":\"IST GEM\u00dcSE PATENTIERBAR?\",\"datePublished\":\"2015-06-22T08:55:07+00:00\",\"dateModified\":\"2021-02-17T11:39:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/\"},\"wordCount\":328,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/propiedad-intelectual-e-industrial.jpg\",\"articleSection\":[\"Urheberrecht und Gewerbliches Eigentum\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/\",\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/\",\"name\":\"IST GEM\u00dcSE PATENTIERBAR?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/propiedad-intelectual-e-industrial.jpg\",\"datePublished\":\"2015-06-22T08:55:07+00:00\",\"dateModified\":\"2021-02-17T11:39:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/propiedad-intelectual-e-industrial.jpg\",\"contentUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/propiedad-intelectual-e-industrial.jpg\",\"width\":669,\"height\":272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/urheberrecht-und-gewerbliches-eigentum\\\/ist-gemuse-patentierbar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vila.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IST GEM\u00dcSE PATENTIERBAR?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vila.es\\\/en\\\/\",\"name\":\"Vil\u00e1 Abogados\",\"description\":\"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vila.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\",\"name\":\"Vil\u00e1 Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"caption\":\"Vil\u00e1 Abogados\"},\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/author\\\/vilaes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IST GEM\u00dcSE PATENTIERBAR?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/","og_locale":"de_DE","og_type":"article","og_title":"IST GEM\u00dcSE PATENTIERBAR?","og_description":"Die j\u00fcngsten Entscheidungen G2\/12 und G2\/13 der Gro\u00dfen Beschwerdekammer des Europ\u00e4ischen Patentamts (\u201eEP\u201c), vom 25. M\u00e4rz 2015, sind nicht ohne Polemik empfangen worden. Beide best\u00e4tigen, dass Erzeugnispatente auf Pflanzen und Pflanzenmaterial erteilt werden k\u00f6nnen, was im Prinzip dem Verbot des Artikels 53 (b), welches a priori biologische Verfahren zur Z\u00fcchtung von Pflanzen oder Tieren der [...]","og_url":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/","og_site_name":"Vil\u00e1 Abogados","article_published_time":"2015-06-22T08:55:07+00:00","article_modified_time":"2021-02-17T11:39:21+00:00","og_image":[{"width":669,"height":272,"url":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","type":"image\/jpeg"}],"author":"Vil\u00e1 Abogados","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Vil\u00e1 Abogados","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/#article","isPartOf":{"@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/"},"author":{"name":"Vil\u00e1 Abogados","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"headline":"IST GEM\u00dcSE PATENTIERBAR?","datePublished":"2015-06-22T08:55:07+00:00","dateModified":"2021-02-17T11:39:21+00:00","mainEntityOfPage":{"@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/"},"wordCount":328,"commentCount":0,"image":{"@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","articleSection":["Urheberrecht und Gewerbliches Eigentum"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/","url":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/","name":"IST GEM\u00dcSE PATENTIERBAR?","isPartOf":{"@id":"https:\/\/vila.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/#primaryimage"},"image":{"@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","datePublished":"2015-06-22T08:55:07+00:00","dateModified":"2021-02-17T11:39:21+00:00","author":{"@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"breadcrumb":{"@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/#primaryimage","url":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","contentUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","width":669,"height":272},{"@type":"BreadcrumbList","@id":"https:\/\/vila.es\/de\/urheberrecht-und-gewerbliches-eigentum\/ist-gemuse-patentierbar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vila.es\/de\/"},{"@type":"ListItem","position":2,"name":"IST GEM\u00dcSE PATENTIERBAR?"}]},{"@type":"WebSite","@id":"https:\/\/vila.es\/en\/#website","url":"https:\/\/vila.es\/en\/","name":"Vil\u00e1 Abogados","description":"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vila.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904","name":"Vil\u00e1 Abogados","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","caption":"Vil\u00e1 Abogados"},"url":"https:\/\/vila.es\/de\/author\/vilaes\/"}]}},"_links":{"self":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/4376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/comments?post=4376"}],"version-history":[{"count":2,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/4376\/revisions"}],"predecessor-version":[{"id":10244,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/4376\/revisions\/10244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media\/4723"}],"wp:attachment":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media?parent=4376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/categories?post=4376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/tags?post=4376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}