{"id":2000,"date":"2016-07-29T13:55:19","date_gmt":"2016-07-29T13:55:19","guid":{"rendered":"https:\/\/vila.es\/de\/?p=2000"},"modified":"2021-01-12T12:26:40","modified_gmt":"2021-01-12T12:26:40","slug":"der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse","status":"publish","type":"post","link":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/","title":{"rendered":"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE)"},"content":{"rendered":"<p>Bis jetzt gab es keine spezifische europ\u00e4ische Regelung mit Ziel des Schutzes der Gesch\u00e4ftsgeheimnisse vor illoyalen Praktiken widerrechtlicher Aneignung, Kopie, Diebstahl, Spionage, etc. Es geht um die technischen Kenntnisse und unternehmerische Informationen von gro\u00dfem Wert, die nicht ver\u00f6ffentlicht und auch nicht registerrechtlich gesch\u00fctzt werden und die man geheimhalten m\u00f6chte. Es ist richtig, dass die TRIPS-Vereinbarung, in die Wege geleitet durch die Weltwirtschaftsorganisation, die durch die Europ\u00e4ische Union mit Ratsentscheidung 94\/800 angenommen wurde, ein erster Schritt nach vorn war, um eine Abhilfe f\u00fcr die erw\u00e4hnten Praktiken zu schaffen, wenn auch die Mitgliedsstaaten in ihrer Definition von Gesch\u00e4ftsgeheimnis und der illegalen Erlangung eines solchen, nicht \u00fcbereinstimmen. Es bestehen unterschiedliche Normen und verschiedenartige Zivilprozesse f\u00fcr den Fall des Diebstahls von Gesch\u00e4ftsgeheimnissen und der Aufdeckung dieser.<\/p>\n<p>Um einen einheitlichen Schutz der Gesch\u00e4ftsgeheimnisse in der EU sicherzustellen, haben das Parlament und der Rat der EU am 8. Juni 2016 die <span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"http:\/\/www.boe.es\/diario_boe\/txt.php?id=DOUE-L-2016-81073\" target=\"_blank\" rel=\"noopener noreferrer\">Richtlinie 2016\/943<\/a><\/span> \u00fcber den Schutz vertraulichen Know-hows und vertraulicher Gesch\u00e4ftsinformationen<\/p>\n<p>(Gesch\u00e4ftsgeheimnisse) vor rechtswidrigem Erwerb sowie rechtswidriger Nutzung und Offenlegung angenommen, die am 5. Juli 2016 in Kraft getreten ist.<\/p>\n<p><span style=\"text-decoration: underline;\">Was sind Gesch\u00e4ftsgeheimnisse?<\/span><\/p>\n<p>Die Richtlinie definiert als \u201eGesch\u00e4ftsgeheimnis\u201c die (technische oder unternehmerische) Information, die die folgenden Voraussetzungen erf\u00fcllt:<\/p>\n<p style=\"padding-left: 40px;\">(a) Sie sind in dem Sinne geheim, dass sie weder in ihrer Gesamtheit noch in der genauen Anordnung und Zusammensetzung ihrer Bestandteile den Personen in den Kreisen, die \u00fcblicherweise mit dieser Art von Informationen umgehen, allgemein bekannt oder ohne weiteres zug\u00e4nglich sind.<\/p>\n<p style=\"padding-left: 40px;\">(b) sie sind von kommerziellem Wert, weil sie geheim sind.<\/p>\n<p style=\"padding-left: 40px;\">(c) sie sind Gegenstand von den Umst\u00e4nden entsprechenden angemessenen Geheimhaltungsma\u00dfnahmen durch die Person, die die rechtm\u00e4\u00dfige Kontrolle \u00fcber die Informationen besitzt.<\/p>\n<p>Es ist wichtig, hervorzuheben, dass die Richtlinie einige De-minimis Schutzparameter festlegt, sodass die Mitgliedsstaaten bei der \u00dcbernahme der Richtlinie einen weiteren Schutz beschlie\u00dfen k\u00f6nnen, solange sie die Regelungen der Richtlinie zur erlaubten Erlangung, Benutzung und Aufdeckung dieser einhalten.<\/p>\n<p>Die Richtlinie verbietet die Benutzung oder Aufdeckung von Know-How Gesch\u00e4ftsgeheimnissen durch Dritte nicht, sondern macht die Illegalit\u00e4t davon abh\u00e4ngig, wodurch diese verwirklicht wird.<\/p>\n<p>Dem folgend ist die Benutzung oder Aufdeckung <span style=\"text-decoration: underline;\">erlaubt, wenn die Informationen auf eine der folgenden Weisen erlangt wird:<\/span><\/p>\n<p style=\"padding-left: 40px;\">(1) Beobachtung, Untersuchung, R\u00fcckbau oder Testen eines Produkts oder Gegenstands, das bzw. der \u00f6ffentlich verf\u00fcgbar gemacht wurde oder sich im rechtm\u00e4\u00dfigen Besitz des Erwerbers der Information befindet, der keiner rechtsg\u00fcltigen Pflicht zur Beschr\u00e4nkung des Erwerbs des Gesch\u00e4ftsgeheimnisses unterliegt.<\/p>\n<p style=\"padding-left: 40px;\">(2) Inanspruchnahme des Rechts der Arbeitnehmer oder Arbeitnehmervertreter auf Information und Anh\u00f6rung gem\u00e4\u00df dem Unionsrecht sowie gem\u00e4\u00df den Rechtsvorschriften und den Gepflogenheiten der Mitgliedstaaten.<\/p>\n<p style=\"padding-left: 40px;\">(3) Jede andere Vorgehensweise, die unter den gegebenen Umst\u00e4nden mit einer seri\u00f6sen Gesch\u00e4ftspraxis vereinbar ist.<\/p>\n<p>Die Richtlinie \u00f6ffnet durch diese Art der Regelung T\u00fcr und Tor f\u00fcr sehr unterschiedliche Regelungen in der Materie durch die Mitgliedstaaten, indem sie annimmt, Erlangung, Gebrauch und Aufdeckung von Gesch\u00e4ftsgeheimnissen seine legal, wenn dies das Recht der EU oder ihrer Mitgliedstaaten erlaubt.<\/p>\n<p>Im Gegensatz hierzu ist die Erlangung von Gesch\u00e4ftsgeheimnissen <span style=\"text-decoration: underline;\">illegal,<\/span> wenn diese erfolgt durch:<\/p>\n<p style=\"padding-left: 40px;\">(1) unbefugten Zugang zu, unbefugte Aneignung oder unbefugtes Kopieren von Dokumenten, oder Korrespondenz, ohne Erlaubnis durch den Inhaber, die das Gesch\u00e4ftsgeheimnis enthalten oder von welchen man dieses ableiten kann.<\/p>\n<p style=\"padding-left: 40px;\">(2) jedes sonstige Verhalten, das unter den jeweiligen Umst\u00e4nden als mit einer seri\u00f6sen Gesch\u00e4ftspraxis nicht vereinbar gilt.<\/p>\n<p>Ebenfalls als rechtswidrig gilt die Nutzung oder Aufdeckung eines Gesch\u00e4ftsgeheimnisses, wenn die betreffende Person:<\/p>\n<p style=\"padding-left: 40px;\">(1) das Gesch\u00e4ftsgeheimnis rechtswidrig erworben hat.<\/p>\n<p style=\"padding-left: 40px;\">(2) gegen eine Vertraulichkeitsvereinbarung oder eine sonstige Verpflichtung, das Gesch\u00e4ftsgeheimnis nicht offenzulegen verst\u00f6\u00dft.<\/p>\n<p style=\"padding-left: 40px;\">(3) gegen eine vertragliche oder sonstige Verpflichtung zur Beschr\u00e4nkung der Nutzung des Gesch\u00e4ftsgeheimnisses verst\u00f6\u00dft.<\/p>\n<p>Der Erwerb, die Nutzung oder die Offenlegung eines Gesch\u00e4ftsgeheimnisses gilt auch dann als rechtswidrig, wenn eine Person zum Zeitpunkt des Erwerbs wusste oder h\u00e4tte wissen m\u00fcssen, dass sie es von einer Person erhalten hat, die es rechtswidrig benutzt oder offengelegt hat.<\/p>\n<p>Schlie\u00dflich ist das Herstellen, Anbieten oder Inverkehrbringen von rechtsverletzenden Produkten oder die Einfuhr, Ausfuhr oder Lagerung von rechtsverletzenden Produkten f\u00fcr diese Zwecke rechtswidrig, wenn die Person, die diese T\u00e4tigkeiten ausf\u00fchrt, wusste oder h\u00e4tte wissen m\u00fcssen, dass das Gesch\u00e4ftsgeheimnis rechtswidrig genutzt wurde.<\/p>\n<p><span style=\"text-decoration: underline;\">Schutzma\u00dfnahmen und Verfahren<\/span><\/p>\n<p>Die Mitgliedstaaten sehen die Ma\u00dfnahmen, Verfahren und Rechtsbehelfe vor, die erforderlich sind, um einen zivilrechtlichen Schutz f\u00fcr den Fall der Rechtsverletzung zu garantieren.<\/p>\n<p>Dennoch ist die Richtlinie diesbez\u00fcglich sehr unklar, indem sie lediglich allgemeine Prinzipien festlegt, deren Erw\u00e4hnung aufgrund ihrer inh\u00e4renten Logik unn\u00f6tig ist:<\/p>\n<ul>\n<li>Sie werden gerecht, unkompliziert, wirksam und abschreckend sein.<\/li>\n<\/ul>\n<ul>\n<li>Sie werden angemessen sein und eine Behinderung des europ\u00e4ischen Binnenmarktes vermeiden<\/li>\n<li>Es werden Ma\u00dfnahmen gegen den Missbrauch der Ma\u00dfnahmen vorgesehen. In diesem Sinne wird gefordert, dass die Mitgliedstaaten \u00fcber Entsch\u00e4digungsverfahren f\u00fcr die beklagte Seite verf\u00fcgen, sowie \u00fcber Sanktionsverfahren f\u00fcr die unberechtigten Kl\u00e4ger und Anordnungen der Ver\u00f6ffentlichung der in solchen Verfahren getroffenen Entscheidungen.<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\">Vorl\u00e4ufige und vorbeugende Ma\u00dfnahmen<\/span><\/p>\n<p>Die Mitgliedstaaten stellen sicher, dass die zust\u00e4ndigen Gerichte auf Antrag des Inhabers des Gesch\u00e4ftsgeheimnisses eine der folgenden vorl\u00e4ufigen und vorbeugenden Ma\u00dfnahmen gegen den angeblichen Rechtsverletzer anordnen:<\/p>\n<p style=\"padding-left: 40px;\">(a) Vorl\u00e4ufige Einstellung oder gegebenenfalls vorl\u00e4ufiges Verbot der Nutzung oder Offenlegung des Gesch\u00e4ftsgeheimnisses.<\/p>\n<p style=\"padding-left: 40px;\">(b) Verbot des Herstellens, Anbietens, Vermarktens oder der Nutzung rechtsverletzender Produkte oder der Einfuhr, Ausfuhr oder Lagerung rechtsverletzender Produkte f\u00fcr diese Zwecke.<\/p>\n<p style=\"padding-left: 40px;\">(c) Beschlagnahme oder Herausgabe der mutma\u00dflich rechtsverletzenden Produkte, um deren Inverkehrbringen oder ihren Umlauf im Markt zu verhindern.<\/p>\n<p>Die Richtlinie legt dem Antragsteller nicht die Pflicht auf, eine Sicherheit zu hinterlegen, sondern \u00fcberl\u00e4sst diese Frage den Mitgliedstaaten.<\/p>\n<p>Dennoch stellen die Mitgliedstaaten sicher, dass die Gerichte als Alternative die Fortsetzung der angeblich rechtswidrigen Nutzung eines Gesch\u00e4ftsgeheimnisses an die Stellung von Sicherheiten kn\u00fcpfen k\u00f6nnen. In jedem Fall darf die Offenlegung eines Gesch\u00e4ftsgeheimnisses gegen die Stellung von Sicherheiten nicht erlaubt werden.<\/p>\n<p><span style=\"text-decoration: underline;\">Verj\u00e4hrungsfristen der Ma\u00dfnahmen<\/span><\/p>\n<p>Die Verj\u00e4hrungsfristen betragen in keinem Fall weniger als 6 Jahre.<\/p>\n<p><span style=\"text-decoration: underline;\">Schadensersatz<\/span><\/p>\n<p>Bei der Festlegung von Schadensersatz f\u00fcr Sch\u00e4den durch die rechtswidrige Erlangung, den Gebrauch oder die Aufdeckung von Gesch\u00e4ftsgeheimnissen m\u00fcssen die Gerichte der Mitgliedstaaten folgenden Faktoren beachten:<\/p>\n<ul>\n<li>Negative wirtschaftliche Folgen, einschlie\u00dflich entgangener Gewinne<\/li>\n<li>Durch den Rechtsverletzer erzielte unlautere Gewinne.<\/li>\n<li>Andere als wirtschaftliche Faktoren, wie den immateriellen Schaden, obwohl die Richtlinie dieses Konzept nicht genauer definiert und bez\u00fcglich dessen man sich nach den Gesetzen, der Rechtsprechung und der Doktrin der Mitgliedstaaten richten muss.<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\">Umsetzung der Richtlinie<\/span><\/p>\n<p>Die Richtlinie muss durch die Mitgliedstaaten bis zu, 9. Juni 2018 umgesetzt werden.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Eduardo Vil\u00e1<\/p>\n<p>Vil\u00e1 Abogados<\/p>\n<p>&nbsp;<\/p>\n<p>F\u00fcr mehr Informationen, kontaktieren Sie:<\/p>\n<p><a href=\"mailto:va@vila.es\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #3366ff;\">va@vila.es<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>29. Juli 2016<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bis jetzt gab es keine spezifische europ\u00e4ische Regelung mit Ziel des Schutzes der Gesch\u00e4ftsgeheimnisse vor illoyalen Praktiken widerrechtlicher Aneignung, Kopie, Diebstahl, Spionage, etc. Es geht um die technischen Kenntnisse und unternehmerische Informationen von gro\u00dfem Wert, die nicht ver\u00f6ffentlicht und auch nicht registerrechtlich gesch\u00fctzt werden und die man geheimhalten m\u00f6chte. Es ist richtig, dass die TRIPS-Vereinbarung,  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":4723,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[95,92,93],"tags":[],"class_list":["post-2000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gemeinschaftsrecht","category-gesellschaftsrecht","category-urheberrecht-und-gewerbliches-eigentum"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE) - Vil\u00e1 Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE) - Vil\u00e1 Abogados\" \/>\n<meta property=\"og:description\" content=\"Bis jetzt gab es keine spezifische europ\u00e4ische Regelung mit Ziel des Schutzes der Gesch\u00e4ftsgeheimnisse vor illoyalen Praktiken widerrechtlicher Aneignung, Kopie, Diebstahl, Spionage, etc. Es geht um die technischen Kenntnisse und unternehmerische Informationen von gro\u00dfem Wert, die nicht ver\u00f6ffentlicht und auch nicht registerrechtlich gesch\u00fctzt werden und die man geheimhalten m\u00f6chte. Es ist richtig, dass die TRIPS-Vereinbarung, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Vil\u00e1 Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-29T13:55:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-12T12:26:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"669\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vil\u00e1 Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vil\u00e1 Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/\"},\"author\":{\"name\":\"Vil\u00e1 Abogados\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"headline\":\"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE)\",\"datePublished\":\"2016-07-29T13:55:19+00:00\",\"dateModified\":\"2021-01-12T12:26:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/\"},\"wordCount\":1116,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/propiedad-intelectual-e-industrial.jpg\",\"articleSection\":[\"Europ\u00e4ische Union\",\"Gesellschaftsrecht\",\"Urheberrecht und Gewerbliches Eigentum\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/\",\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/\",\"name\":\"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE) - Vil\u00e1 Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/propiedad-intelectual-e-industrial.jpg\",\"datePublished\":\"2016-07-29T13:55:19+00:00\",\"dateModified\":\"2021-01-12T12:26:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/propiedad-intelectual-e-industrial.jpg\",\"contentUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/propiedad-intelectual-e-industrial.jpg\",\"width\":669,\"height\":272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vila.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vila.es\\\/en\\\/\",\"name\":\"Vil\u00e1 Abogados\",\"description\":\"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vila.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\",\"name\":\"Vil\u00e1 Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"caption\":\"Vil\u00e1 Abogados\"},\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/author\\\/vilaes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE) - Vil\u00e1 Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/","og_locale":"de_DE","og_type":"article","og_title":"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE) - Vil\u00e1 Abogados","og_description":"Bis jetzt gab es keine spezifische europ\u00e4ische Regelung mit Ziel des Schutzes der Gesch\u00e4ftsgeheimnisse vor illoyalen Praktiken widerrechtlicher Aneignung, Kopie, Diebstahl, Spionage, etc. Es geht um die technischen Kenntnisse und unternehmerische Informationen von gro\u00dfem Wert, die nicht ver\u00f6ffentlicht und auch nicht registerrechtlich gesch\u00fctzt werden und die man geheimhalten m\u00f6chte. Es ist richtig, dass die TRIPS-Vereinbarung, [...]","og_url":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/","og_site_name":"Vil\u00e1 Abogados","article_published_time":"2016-07-29T13:55:19+00:00","article_modified_time":"2021-01-12T12:26:40+00:00","og_image":[{"width":669,"height":272,"url":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","type":"image\/jpeg"}],"author":"Vil\u00e1 Abogados","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Vil\u00e1 Abogados","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/#article","isPartOf":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/"},"author":{"name":"Vil\u00e1 Abogados","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"headline":"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE)","datePublished":"2016-07-29T13:55:19+00:00","dateModified":"2021-01-12T12:26:40+00:00","mainEntityOfPage":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/"},"wordCount":1116,"commentCount":0,"image":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","articleSection":["Europ\u00e4ische Union","Gesellschaftsrecht","Urheberrecht und Gewerbliches Eigentum"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/","url":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/","name":"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE) - Vil\u00e1 Abogados","isPartOf":{"@id":"https:\/\/vila.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/#primaryimage"},"image":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","datePublished":"2016-07-29T13:55:19+00:00","dateModified":"2021-01-12T12:26:40+00:00","author":{"@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"breadcrumb":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/#primaryimage","url":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","contentUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/propiedad-intelectual-e-industrial.jpg","width":669,"height":272},{"@type":"BreadcrumbList","@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/der-schutz-des-know-und-der-unternehmerischen-informationen-geschaftsgeheimnisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vila.es\/de\/"},{"@type":"ListItem","position":2,"name":"DER SCHUTZ DES KNOW-HOW UND DER UNTERNEHMERISCHEN INFORMATIONEN (GESCH\u00c4FTSGEHEIMNISSE)"}]},{"@type":"WebSite","@id":"https:\/\/vila.es\/en\/#website","url":"https:\/\/vila.es\/en\/","name":"Vil\u00e1 Abogados","description":"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vila.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904","name":"Vil\u00e1 Abogados","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","caption":"Vil\u00e1 Abogados"},"url":"https:\/\/vila.es\/de\/author\/vilaes\/"}]}},"_links":{"self":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/2000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/comments?post=2000"}],"version-history":[{"count":3,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/2000\/revisions"}],"predecessor-version":[{"id":9453,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/2000\/revisions\/9453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media\/4723"}],"wp:attachment":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media?parent=2000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/categories?post=2000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/tags?post=2000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}