{"id":13984,"date":"2024-11-22T14:32:21","date_gmt":"2024-11-22T14:32:21","guid":{"rendered":"https:\/\/vila.es\/?p=13984"},"modified":"2024-11-25T16:58:19","modified_gmt":"2024-11-25T16:58:19","slug":"neue-aktien-mit-mehrfachstimmrecht","status":"publish","type":"post","link":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/","title":{"rendered":"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT"},"content":{"rendered":"<p style=\"text-align: right;\"><strong><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/vila.es\/societario\/las-nuevas-acciones-con-derecho-de-voto-multiple\/\">ES<\/a><\/span>|<span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/vila.es\/en\/corporate\/new-shares-with-multiple-voting-rights\/\">EN<\/a><\/span>|<span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/vila.es\/ja\/%e4%bc%9a%e7%a4%be%e6%b3%95\/%e6%96%b0%e8%a6%8f%e8%a4%87%e6%95%b0%e8%ad%b0%e6%b1%ba%e6%a8%a9%e4%bb%98%e6%a0%aa%e5%bc%8f\/\">\u65e5\u672c\u8a9e<\/a><\/span>|DE<\/strong><\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Am 23. Oktober 2024 wurde die Richtlinie (EU) 2024\/2810 verabschiedet, die sich auf Aktienstrukturen mit Mehrfachstimmrechten f\u00fcr Unternehmen bezieht, die eine Zulassung f\u00fcr ein multilaterales Handelssystem (MHS) anstreben.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Zun\u00e4chst ist klarzustellen, dass es sich bei einem &#8222;multilateralen Handelssystem&#8220; (MTF) um eine von einer Wertpapierfirma oder einem Marktbetreiber betriebene Handelsplattform handelt, die es erm\u00f6glicht, Kauf- und Verkaufsinteressen an Finanzinstrumenten zusammenzuf\u00fchren, um Vertr\u00e4ge zu schlie\u00dfen; das Konzept umfasst sowohl geregelte M\u00e4rkte als auch KMU-Wachstumsm\u00e4rkte (M\u00e4rkte, auf denen mindestens 50 % der Emittenten der zugelassenen Finanzinstrumente KMU sind). Es sollte auch von vornherein klargestellt werden, dass so genannte &#8222;Treueaktionen&#8220; nicht in den Anwendungsbereich der Richtlinie fallen.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">In Anbetracht der Erw\u00e4gungsgr\u00fcnde der Richtlinie zielt die Mehrfachstimmrechtsstruktur darauf ab, die Attraktivit\u00e4t der Notierung auf Handelsplattformen f\u00fcr KMU als Mittel zur Kapitalbeschaffung zu erh\u00f6hen. Ziel ist es nicht, Anreize f\u00fcr die B\u00f6rsennotierung von KMU und den st\u00e4ndigen Austausch von Aktienbesitz zu schaffen, sondern den Einstieg von stabilen und engagierten Investoren in das Unternehmen auf mittlere bis lange Sicht zu erm\u00f6glichen. Bislang schreckt vor allem die Angst vor dem Verlust der Kontrolle \u00fcber das Unternehmen durch die Gr\u00fcndungs- oder Hauptaktion\u00e4re vom Zugang zu einem \u00f6ffentlichen Markt ab, da die B\u00f6rsennotierung f\u00fcr sie eine Verw\u00e4sserung der Eigentumsrechte bedeuten kann.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Mit Aktien mit Mehrfachstimmrecht wird es m\u00f6glich sein, Zugang zu \u00f6ffentlichen M\u00e4rkten zu erhalten, um Finanzmittel au\u00dferhalb der traditionellen Finanzkan\u00e4le zu beschaffen, ohne dass dieser Vorteil durch den Verlust der Kontrolle \u00fcber das Unternehmen erkauft werden muss.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Die in der Richtlinie vorgeschlagene Formel sieht die Ausgabe von zwei Aktiengattungen vor: Die erste Gattung wird von den Aktion\u00e4ren im Verh\u00e4ltnis zum eingebrachten Kapital ausgegeben und ist mit einem zum Kapital proportionalen Stimmrecht ausgestattet, w\u00e4hrend die zweite Aktiengattung den Inhabern jeder Aktie das Recht verleiht, zwei oder mehr Stimmen abzugeben (wie in der Satzung festgelegt), so dass im letzteren Fall keine Proportionalit\u00e4t zum Nennwert dieser Aktien besteht.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Aktien mit Mehrfachstimmrecht werden von Mehrheitsaktion\u00e4ren gehalten, so dass sie, auch wenn sie weniger Aktien halten als andere Aktion\u00e4re, die durch den Kauf auf dem \u00f6ffentlichen Markt Zugang zu ihnen erhalten haben, dank der gr\u00f6\u00dferen Anzahl von Stimmen, die ihnen durch ihre Aktien mit Mehrfachstimmrecht verliehen werden, die Gesellschaft dennoch kontrollieren.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Die Einf\u00fchrung dieses Mechanismus schlie\u00dft jedoch die M\u00f6glichkeit anderer Mechanismen zur St\u00e4rkung der Aktion\u00e4rsmacht aus, wie Aktien ohne Stimmrecht, Aktien mit Vetorecht bei Hauptversammlungsbeschl\u00fcssen und sogar Treueaktien. Diese Unvereinbarkeit hat zur Folge, dass Unternehmen, die in ihren Satzungen \u00fcber andere alternative Mechanismen verf\u00fcgen, diese bei der Genehmigung der Struktur von Aktien mit Mehrfachstimmrecht ausschlie\u00dfen m\u00fcssen.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Vielleicht ist das Hauptmotiv der Richtlinie, eine uneinheitliche Regulierung von Mehrfachstimmrechtsanteilen in den Mitgliedstaaten der Europ\u00e4ischen Union oder sogar deren Verbot in einigen Staaten zu verhindern. In der Richtlinie wird argumentiert, dass eine solche Ungleichheit zur Schaffung von Hindernissen f\u00fcr den freien Kapitalverkehr innerhalb des EU-Marktes f\u00fchren w\u00fcrde. Dies ist nicht unkritisch, da die Richtlinie selbst, wie noch zu zeigen sein wird, den Mitgliedstaaten einen relativ gro\u00dfen Spielraum bei der Festlegung bestimmter Garantien f\u00fcr die Aus\u00fcbung von Mehrstimmrechten l\u00e4sst, was letztlich zu nicht unerheblichen Unterschieden zwischen den L\u00e4ndern f\u00fchren kann.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Was die formalen Anforderungen betrifft, so m\u00fcssen Gesellschaften, die eine Mehrstimmrechtsstruktur einrichten wollen, dies auf der Hauptversammlung mit qualifizierter Mehrheit beschlie\u00dfen und in ihre Satzung aufnehmen. Die Einf\u00fchrung einer solchen Struktur kann vor der Zulassung der Aktien zu einem multilateralen Handelssystem wirksam werden.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Sobald die Struktur geschaffen ist, erlaubt die Richtlinie den Mitgliedstaaten, die tats\u00e4chliche Aus\u00fcbung des Mehrstimmrechts vom Zugang der Gesellschaft zum multilateralen Handelssystem abh\u00e4ngig zu machen, was insofern vern\u00fcnftig erscheint, als der Zweck der Mehrstimmrechtsstruktur der Zugang zu solchen Handelsm\u00e4rkten ist.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Aktien mit Mehrfachstimmrecht k\u00f6nnen sowohl bei Namens- als auch bei Inhaberaktien ausgegeben werden, da die Richtlinie diesbez\u00fcglich keine Verbote oder Beschr\u00e4nkungen vorsieht.\u00a0 In jedem Fall m\u00fcssen sie jedoch durch buchm\u00e4\u00dfige Eintragungen vertreten sein, die entweder mit Hilfe der Blockchain-Technologie oder mit verteilten Registern registriert werden, einem technischen Hilfsmittel, das die Echtheit, Unver\u00e4nderbarkeit und R\u00fcckverfolgbarkeit der Aktien gew\u00e4hrleistet.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Einer der Haupteinw\u00e4nde gegen die Struktur von Aktien mit mehreren Stimmrechten ist das Risiko des Machtmissbrauchs durch Aktion\u00e4re, die solche Aktien halten. Die Festlegung von Beschr\u00e4nkungen oder &#8222;Schutzma\u00dfnahmen f\u00fcr Minderheitsaktion\u00e4re&#8220; kann jedoch einen unangemessenen Eingriff in das soziale Leben und die Organisationsstruktur von Unternehmen darstellen und zu regulatorischen Unterschieden zwischen den Mitgliedstaaten f\u00fchren. Es gibt zwei Arten von Schutzklauseln: obligatorische und fakultative.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Zu den Schutzma\u00dfnahmen, die die Mitgliedstaaten in ihre Rechtsvorschriften aufnehmen m\u00fcssen, geh\u00f6ren die folgenden:<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">A) Die Mitgliedstaaten m\u00fcssen eine H\u00f6chstzahl von Stimmen pro Aktie festlegen (maximales Verh\u00e4ltnis zwischen der Anzahl der Stimmen, die mit einer Aktie mit Mehrfachstimmrecht verbunden sind, und der Anzahl der Stimmen von Aktien mit geringerem Stimmrecht). Die Richtlinie legt jedoch keine Spanne oder eine bestimmte Zahl fest, sondern \u00fcberl\u00e4sst dies dem Ermessen der Mitgliedstaaten.<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">B) Alternativ oder kumulativ zu den vorgenannten Bestimmungen beschr\u00e4nken die Mitgliedstaaten das Mehrstimmrecht f\u00fcr Beschl\u00fcsse, die nach dem Recht des Mitgliedstaats eine qualifizierte Mehrheit erfordern. In diesen F\u00e4llen muss die Mehrheit entweder eine qualifizierte Mehrheit der abgegebenen Stimmen und des bei der Versammlung vertretenen Grundkapitals oder eine qualifizierte Mehrheit der abgegebenen Stimmen und eine gesonderte Abstimmung f\u00fcr jede Aktiengattung, deren Stimmen betroffen sind, umfassen.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Wichtig ist, dass Entscheidungen \u00fcber die Ernennung und Abberufung von Mitgliedern des Leitungsorgans, Management- und Aufsichtsangelegenheiten sowie operative Entscheidungen, die eine qualifizierte Mehrheit erfordern, von dieser Beschr\u00e4nkung der erweiterten Stimmabgabe ausgenommen sind.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Die Mitgliedstaaten k\u00f6nnen nach eigenem Ermessen auch andere Schutzma\u00dfnahmen in Bezug auf das Erl\u00f6schen von Aktien mit Mehrfachstimmrechten einf\u00fchren, einschlie\u00dflich der Zulassung von:<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">(a) Sunset-Klauseln, die auf der \u00dcbertragung von Aktien mit erh\u00f6htem Stimmrecht entweder unter Lebenden oder von Todes wegen beruhen.<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">(b) Sunset-Klauseln, die auf dem Zeitablauf beruhen, obwohl die Richtlinie keine spezifische Frist vorsieht.<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">(c) Beendigungsklauseln, die auf dem Eintreten eines bestimmten Umstands oder Ereignisses beruhen.<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">(d) Andere Klauseln, die im Ermessen des Mitgliedstaates liegen, da die Richtlinie keine geschlossene Anzahl von Schutzklauseln vorsieht, in Artikel 4.2 sind jedoch drei davon beispielhaft aufgef\u00fchrt.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Erw\u00e4gungsgrund Nr. 19 der Richtlinie besagt, dass zus\u00e4tzliche Stimmrechte, die mit Mehrstimmrechtsaktien verbunden sind, nicht dazu verwendet werden d\u00fcrfen, das Unternehmen an der Einhaltung von EU-Umwelt- oder Grundrechtsvorschriften zu hindern. Diese vage Aussage wurde jedoch nicht abschlie\u00dfend in den Artikeln der Richtlinie konkretisiert, so dass die Aussage als programmatische Geste ideologischen Charakters, aber ohne verbindliche \u00dcbersetzung f\u00fcr die EU-Staaten interpretiert werden muss, ganz abgesehen von den wahrscheinlichen negativen Auswirkungen, die sie auf den Zweck von Mehrstimmrechtsstrukturen gehabt h\u00e4tte, wenn sie schlie\u00dflich als Verpflichtung integriert worden w\u00e4re.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Abschlie\u00dfend werden wir auf einige Verpflichtungen in Bezug auf die Transparenz oder das Recht auf Information hinweisen, die Unternehmen, die sich f\u00fcr die Einrichtung einer Mehrstimmrechtsaktienstruktur entscheiden, beachten m\u00fcssen:<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">(i) In den Prospekten f\u00fcr die Zulassung der Aktien zum Handel auf dem KMU-Markt und im Jahresfinanzbericht die Aktienstruktur des Unternehmens anzugeben, wobei die Aktiengattungen, ihre Rechte und Pflichten (sowohl die zum Handel zugelassenen als auch die au\u00dferhalb des Handels verbleibenden), die Gesamtzahl der Aktien und die von ihnen vertretenen Stimmen anzugeben sind.<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">(ii) Berichterstattung \u00fcber etwaige Beschr\u00e4nkungen bei der \u00dcbertragung von Aktien, gegebenenfalls unter Angabe der Bestimmungen der Aktion\u00e4rsvereinbarungen, die dies verhindern.<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">(iii) Meldung der Identit\u00e4t von Aktion\u00e4ren, die Aktien mit Mehrfachstimmrecht halten, oder von Bevollm\u00e4chtigten, die Stimmrechte aus\u00fcben und mehr als 5 % der Stimmrechte der Gesellschaft besitzen.<\/p>\n<p style=\"padding-left: 40px; text-align: justify;\">(iv) Identifizierung der Gesellschaft mit einer Struktur von zum Handel zugelassenen Aktien mit Mehrfachstimmrechten mittels einer vom Marktbetreiber festzulegenden Kennzeichnung, obwohl die Richtlinie dies in ihren Erw\u00e4gungsgr\u00fcnden (Erw\u00e4gungsgrund 18) erw\u00e4hnt und nicht ausdr\u00fccklich festlegt, sondern einem k\u00fcnftigen technischen Projekt anvertraut, das von der Europ\u00e4ischen Kommission zu entwickeln ist.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Die Richtlinie muss bis sp\u00e4testens 5. Dezember 2026 in das Recht der Mitgliedstaaten umgesetzt werden.\u00a0 Die praktischen Auswirkungen auf den Markt und insbesondere auf die St\u00e4rkung der KMU, die sich f\u00fcr die Struktur mit mehreren Stimmrechtsanteilen entscheiden, scheinen jedoch auf den ersten Blick nicht klar zu sein, auch wenn sie sich in der Europ\u00e4ischen Union nicht einheitlich auswirken wird, da die Eigenheiten der nat\u00fcrlichen Personen, die die KMU kontrollieren, sehr unterschiedlich sind, insbesondere in Spanien, wo die \u00fcberwiegende Mehrheit der KMU in Familienbesitz und geschlossen ist. Dies schlie\u00dft nicht aus, dass das System ein praktisches Mittel zur Finanzierung von jungen oder etablierten KMU mit attraktiven Projekten darstellt, deren Solvenz oder Sicherheiten es ihnen erschweren w\u00fcrden, Finanzmittel auf traditionellem Wege zu erhalten, und die andererseits im Rahmen eines multilateralen Finanzierungssystems (und zu relativ geringen Kosten) die Nachfrage risikofreudiger und renditestarker Investoren befriedigen k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Eduardo Vil\u00e1<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Vil\u00e1 Abogados<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">F\u00fcr weitere Informationen, wenden Sie sich an:<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"color: #3366ff;\"> <a style=\"color: #3366ff;\" href=\"mailto:va@vila.es\">va@vila.es<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">22. November 2024<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ES|EN|\u65e5\u672c\u8a9e|DE Am 23. Oktober 2024 wurde die Richtlinie (EU) 2024\/2810 verabschiedet, die sich auf Aktienstrukturen mit Mehrfachstimmrechten f\u00fcr Unternehmen bezieht, die eine Zulassung f\u00fcr ein multilaterales Handelssystem (MHS) anstreben. Zun\u00e4chst ist klarzustellen, dass es sich bei einem &#8222;multilateralen Handelssystem&#8220; (MTF) um eine von einer Wertpapierfirma oder einem Marktbetreiber betriebene Handelsplattform handelt, die es erm\u00f6glicht, Kauf-  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":5987,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[],"class_list":["post-13984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaftsrecht"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NEUE AKTIEN MIT MEHRFACHSTIMMRECHT - Vil\u00e1 Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT - Vil\u00e1 Abogados\" \/>\n<meta property=\"og:description\" content=\"ES|EN|\u65e5\u672c\u8a9e|DE Am 23. Oktober 2024 wurde die Richtlinie (EU) 2024\/2810 verabschiedet, die sich auf Aktienstrukturen mit Mehrfachstimmrechten f\u00fcr Unternehmen bezieht, die eine Zulassung f\u00fcr ein multilaterales Handelssystem (MHS) anstreben. Zun\u00e4chst ist klarzustellen, dass es sich bei einem &#8222;multilateralen Handelssystem&#8220; (MTF) um eine von einer Wertpapierfirma oder einem Marktbetreiber betriebene Handelsplattform handelt, die es erm\u00f6glicht, Kauf- [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/\" \/>\n<meta property=\"og:site_name\" content=\"Vil\u00e1 Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-22T14:32:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-25T16:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/societario2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"669\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vil\u00e1 Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vil\u00e1 Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/\"},\"author\":{\"name\":\"Vil\u00e1 Abogados\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"headline\":\"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT\",\"datePublished\":\"2024-11-22T14:32:21+00:00\",\"dateModified\":\"2024-11-25T16:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/\"},\"wordCount\":1514,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/societario2.jpg\",\"articleSection\":[\"Gesellschaftsrecht\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/\",\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/\",\"name\":\"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT - Vil\u00e1 Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/societario2.jpg\",\"datePublished\":\"2024-11-22T14:32:21+00:00\",\"dateModified\":\"2024-11-25T16:58:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/societario2.jpg\",\"contentUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/societario2.jpg\",\"width\":669,\"height\":272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gesellschaftsrecht\\\/neue-aktien-mit-mehrfachstimmrecht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vila.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vila.es\\\/en\\\/\",\"name\":\"Vil\u00e1 Abogados\",\"description\":\"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vila.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\",\"name\":\"Vil\u00e1 Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"caption\":\"Vil\u00e1 Abogados\"},\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/author\\\/vilaes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT - Vil\u00e1 Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/","og_locale":"de_DE","og_type":"article","og_title":"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT - Vil\u00e1 Abogados","og_description":"ES|EN|\u65e5\u672c\u8a9e|DE Am 23. Oktober 2024 wurde die Richtlinie (EU) 2024\/2810 verabschiedet, die sich auf Aktienstrukturen mit Mehrfachstimmrechten f\u00fcr Unternehmen bezieht, die eine Zulassung f\u00fcr ein multilaterales Handelssystem (MHS) anstreben. Zun\u00e4chst ist klarzustellen, dass es sich bei einem &#8222;multilateralen Handelssystem&#8220; (MTF) um eine von einer Wertpapierfirma oder einem Marktbetreiber betriebene Handelsplattform handelt, die es erm\u00f6glicht, Kauf- [...]","og_url":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/","og_site_name":"Vil\u00e1 Abogados","article_published_time":"2024-11-22T14:32:21+00:00","article_modified_time":"2024-11-25T16:58:19+00:00","og_image":[{"width":669,"height":272,"url":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/societario2.jpg","type":"image\/jpeg"}],"author":"Vil\u00e1 Abogados","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Vil\u00e1 Abogados","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/#article","isPartOf":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/"},"author":{"name":"Vil\u00e1 Abogados","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"headline":"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT","datePublished":"2024-11-22T14:32:21+00:00","dateModified":"2024-11-25T16:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/"},"wordCount":1514,"commentCount":0,"image":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/societario2.jpg","articleSection":["Gesellschaftsrecht"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/","url":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/","name":"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT - Vil\u00e1 Abogados","isPartOf":{"@id":"https:\/\/vila.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/#primaryimage"},"image":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/societario2.jpg","datePublished":"2024-11-22T14:32:21+00:00","dateModified":"2024-11-25T16:58:19+00:00","author":{"@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"breadcrumb":{"@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/#primaryimage","url":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/societario2.jpg","contentUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/societario2.jpg","width":669,"height":272},{"@type":"BreadcrumbList","@id":"https:\/\/vila.es\/de\/gesellschaftsrecht\/neue-aktien-mit-mehrfachstimmrecht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vila.es\/de\/"},{"@type":"ListItem","position":2,"name":"NEUE AKTIEN MIT MEHRFACHSTIMMRECHT"}]},{"@type":"WebSite","@id":"https:\/\/vila.es\/en\/#website","url":"https:\/\/vila.es\/en\/","name":"Vil\u00e1 Abogados","description":"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vila.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904","name":"Vil\u00e1 Abogados","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","caption":"Vil\u00e1 Abogados"},"url":"https:\/\/vila.es\/de\/author\/vilaes\/"}]}},"_links":{"self":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/13984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/comments?post=13984"}],"version-history":[{"count":3,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/13984\/revisions"}],"predecessor-version":[{"id":13995,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/13984\/revisions\/13995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media\/5987"}],"wp:attachment":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media?parent=13984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/categories?post=13984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/tags?post=13984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}