{"id":12299,"date":"2023-03-31T07:43:50","date_gmt":"2023-03-31T07:43:50","guid":{"rendered":"https:\/\/vila.es\/?p=12299"},"modified":"2023-04-05T07:21:35","modified_gmt":"2023-04-05T07:21:35","slug":"sortenschutz-entschaedigung-fuer-illegalen-anbau","status":"publish","type":"post","link":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/","title":{"rendered":"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: justify;\">Der Gerichtshof der Europ\u00e4ischen Union (im Folgenden &#8222;EuGH&#8220;) hat soeben ein Urteil gef\u00e4llt, in dem er die Art und Weise des Schadensersatzes f\u00fcr den unerlaubten Anbau einer gesch\u00fctzten Pflanzensorte neu definiert (Urteil vom 16. M\u00e4rz 2023, Rechtssache C-522\/21).<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">In der Rechtssache vor dem Gerichtshof ging es um eine Schadensersatzklage der STV, einer Vereinigung von Inhabern gesch\u00fctzter Pflanzensorten, gegen einen Landwirt, dem vorgeworfen wurde, eine nach der Verordnung (EG) Nr. 2100\/94 gesch\u00fctzte Sorte von Wintergerste, KWS Meridian, ohne Genehmigung angebaut zu haben.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Bei der Festsetzung der Entsch\u00e4digung pr\u00fcfte das mit dem Fall befasste deutsche Gericht die G\u00fcltigkeit von Artikel 18 Absatz 2 der Verordnung (EG) Nr. 1768\/95 (zur Durchf\u00fchrung der Verordnung (EG) Nr. 2100\/94), wonach ein Landwirt, der es wiederholt und vors\u00e4tzlich unterlassen hat, dem Inhaber der gesch\u00fctzten Sorte eine angemessene Verg\u00fctung zu zahlen, zur Zahlung einer Entsch\u00e4digung verpflichtet sein kann, die mindestens &#8222;einem Pauschalbetrag entspricht, der auf der Grundlage des Vierfachen des f\u00fcr die genehmigte Erzeugung durchschnittlich erhobenen Betrags berechnet wird&#8220;. In Anbetracht dieser Situation hat das Gericht dem EuGH eine Frage zur Vorabentscheidung \u00fcber die G\u00fcltigkeit dieses Artikels vorgelegt.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Nach Ansicht des EuGH verst\u00f6\u00dft die Festsetzung eines Pauschalbetrags als Entsch\u00e4digung gegen Artikel 94 Absatz 2 der Verordnung (EG) Nr. 2100\/94, wonach derjenige, der vors\u00e4tzlich oder fahrl\u00e4ssig eine Rechtsverletzung begeht, dem Sortenschutzinhaber zum Ersatz des entstandenen Schadens verpflichtet ist und der Entsch\u00e4digungsanspruch im Falle leichter Fahrl\u00e4ssigkeit entsprechend gek\u00fcrzt werden kann. Mit Artikel 94 Absatz 2 soll der Sortenschutzinhaber f\u00fcr den vom Verletzer unrechtm\u00e4\u00dfig erlangten Vorteil finanziell entsch\u00e4digt werden, der sich in der H\u00f6he der von ihm nicht gezahlten Lizenzgeb\u00fchr f\u00fcr die Nutzung der gesch\u00fctzten Sorte beziffern l\u00e4sst (im Folgenden &#8222;angemessene Entsch\u00e4digung&#8220;). Der in Artikel 94 Absatz 2 vorgesehene Anspruch auf Entsch\u00e4digung beruht daher auf einer objektiven Grundlage, wie dem tats\u00e4chlich entstandenen Schaden, so dass dieser Artikel nicht dazu verwendet werden kann, einen pauschalen Aufschlag f\u00fcr die Verletzung zu erheben, der nicht diesem tats\u00e4chlichen Schaden entspricht. Mit anderen Worten: Artikel 94 Absatz 2 sieht keinen Ersatz f\u00fcr andere Sch\u00e4den als die Nichtzahlung der Lizenzgeb\u00fchr vor.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Dar\u00fcber hinaus liegt f\u00fcr den EuGH die Beweislast f\u00fcr den Nachweis, dass der erlittene Schaden gr\u00f6\u00dfer ist als der durch die angemessene Entsch\u00e4digung abgedeckte, beim Sorteninhaber. Die H\u00f6he der Lizenzgeb\u00fchr an sich kann nicht die Grundlage f\u00fcr eine h\u00f6here Entsch\u00e4digung sein, da sie nicht notwendigerweise mit dem entstandenen Schaden in Zusammenhang steht.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Der Gerichtshof ist der Auffassung, dass es Sache des Richters ist, zu bestimmen, wie der vom Rechtsinhaber behauptete Schaden nachzuweisen ist und ob zus\u00e4tzlich zu der angemessenen Entsch\u00e4digung ein Pauschalbetrag festgesetzt werden sollte, um den entstandenen Schaden vollst\u00e4ndig zu ersetzen. Andernfalls w\u00e4re der Rechtsinhaber nicht verpflichtet, den erlittenen Schaden nachzuweisen, sondern nur das Vorliegen einer wiederholten und vors\u00e4tzlichen Verletzung seiner Rechte, was zu einer \u00dcberkompensation f\u00fchren k\u00f6nnte.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Mit anderen Worten: Die Festsetzung eines Pauschalbetrags als Entsch\u00e4digung w\u00fcrde eine Vermutung iuris et de iure f\u00fcr das Vorliegen eines Schadens darstellen, der gr\u00f6\u00dfer ist als derjenige, der sich aus der Nichtzahlung der Lizenzgeb\u00fchr ergibt, und die Befugnis des Gerichts einschr\u00e4nken, die Entsch\u00e4digung entsprechend dem tats\u00e4chlich vom Rechtsinhaber erlittenen Schaden festzusetzen, da das Gericht den in Artikel 18.2 festgesetzten Mindestbetrag nur erh\u00f6hen, aber niemals verringern kann, selbst wenn feststeht, dass der entstandene Schaden geringer ist als derjenige, der sich aus der Anwendung dieses Artikels ergibt.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Aus all diesen Gr\u00fcnden erkl\u00e4rt der EuGH Artikel 18 Absatz 2 der Verordnung (EG) Nr. 1768\/95 f\u00fcr null und nichtig.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Joan Llu\u00eds Rubio<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Vil\u00e1 Abogados<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">F\u00fcr weitere Informationen wenden Sie sich bitte an:<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"mailto:va@vila.es\">va@vila.es<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">31. M\u00e4rz 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Gerichtshof der Europ\u00e4ischen Union (im Folgenden &#8222;EuGH&#8220;) hat soeben ein Urteil gef\u00e4llt, in dem er die Art und Weise des Schadensersatzes f\u00fcr den unerlaubten Anbau einer gesch\u00fctzten Pflanzensorte neu definiert (Urteil vom 16. M\u00e4rz 2023, Rechtssache C-522\/21). In der Rechtssache vor dem Gerichtshof ging es um eine Schadensersatzklage der STV, einer Vereinigung von Inhabern  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":4747,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[95],"tags":[],"class_list":["post-12299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gemeinschaftsrecht"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU - Vil\u00e1 Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU - Vil\u00e1 Abogados\" \/>\n<meta property=\"og:description\" content=\"Der Gerichtshof der Europ\u00e4ischen Union (im Folgenden &#8222;EuGH&#8220;) hat soeben ein Urteil gef\u00e4llt, in dem er die Art und Weise des Schadensersatzes f\u00fcr den unerlaubten Anbau einer gesch\u00fctzten Pflanzensorte neu definiert (Urteil vom 16. M\u00e4rz 2023, Rechtssache C-522\/21). In der Rechtssache vor dem Gerichtshof ging es um eine Schadensersatzklage der STV, einer Vereinigung von Inhabern [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/\" \/>\n<meta property=\"og:site_name\" content=\"Vil\u00e1 Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-31T07:43:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-05T07:21:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/ue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"669\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vil\u00e1 Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vil\u00e1 Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/\"},\"author\":{\"name\":\"Vil\u00e1 Abogados\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"headline\":\"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU\",\"datePublished\":\"2023-03-31T07:43:50+00:00\",\"dateModified\":\"2023-04-05T07:21:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/\"},\"wordCount\":638,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ue.jpg\",\"articleSection\":[\"Europ\u00e4ische Union\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/\",\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/\",\"name\":\"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU - Vil\u00e1 Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ue.jpg\",\"datePublished\":\"2023-03-31T07:43:50+00:00\",\"dateModified\":\"2023-04-05T07:21:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ue.jpg\",\"contentUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ue.jpg\",\"width\":669,\"height\":272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/gemeinschaftsrecht\\\/sortenschutz-entschaedigung-fuer-illegalen-anbau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vila.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vila.es\\\/en\\\/\",\"name\":\"Vil\u00e1 Abogados\",\"description\":\"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vila.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\",\"name\":\"Vil\u00e1 Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"caption\":\"Vil\u00e1 Abogados\"},\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/author\\\/vilaes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU - Vil\u00e1 Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/","og_locale":"de_DE","og_type":"article","og_title":"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU - Vil\u00e1 Abogados","og_description":"Der Gerichtshof der Europ\u00e4ischen Union (im Folgenden &#8222;EuGH&#8220;) hat soeben ein Urteil gef\u00e4llt, in dem er die Art und Weise des Schadensersatzes f\u00fcr den unerlaubten Anbau einer gesch\u00fctzten Pflanzensorte neu definiert (Urteil vom 16. M\u00e4rz 2023, Rechtssache C-522\/21). In der Rechtssache vor dem Gerichtshof ging es um eine Schadensersatzklage der STV, einer Vereinigung von Inhabern [...]","og_url":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/","og_site_name":"Vil\u00e1 Abogados","article_published_time":"2023-03-31T07:43:50+00:00","article_modified_time":"2023-04-05T07:21:35+00:00","og_image":[{"width":669,"height":272,"url":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/ue.jpg","type":"image\/jpeg"}],"author":"Vil\u00e1 Abogados","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Vil\u00e1 Abogados","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/#article","isPartOf":{"@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/"},"author":{"name":"Vil\u00e1 Abogados","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"headline":"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU","datePublished":"2023-03-31T07:43:50+00:00","dateModified":"2023-04-05T07:21:35+00:00","mainEntityOfPage":{"@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/"},"wordCount":638,"commentCount":0,"image":{"@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/ue.jpg","articleSection":["Europ\u00e4ische Union"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/","url":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/","name":"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU - Vil\u00e1 Abogados","isPartOf":{"@id":"https:\/\/vila.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/#primaryimage"},"image":{"@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/ue.jpg","datePublished":"2023-03-31T07:43:50+00:00","dateModified":"2023-04-05T07:21:35+00:00","author":{"@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"breadcrumb":{"@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/#primaryimage","url":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/ue.jpg","contentUrl":"https:\/\/vila.es\/wp-content\/uploads\/2020\/07\/ue.jpg","width":669,"height":272},{"@type":"BreadcrumbList","@id":"https:\/\/vila.es\/de\/gemeinschaftsrecht\/sortenschutz-entschaedigung-fuer-illegalen-anbau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vila.es\/de\/"},{"@type":"ListItem","position":2,"name":"SORTENSCHUTZ: ENTSCH\u00c4DIGUNG F\u00dcR ILLEGALEN ANBAU"}]},{"@type":"WebSite","@id":"https:\/\/vila.es\/en\/#website","url":"https:\/\/vila.es\/en\/","name":"Vil\u00e1 Abogados","description":"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vila.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904","name":"Vil\u00e1 Abogados","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","caption":"Vil\u00e1 Abogados"},"url":"https:\/\/vila.es\/de\/author\/vilaes\/"}]}},"_links":{"self":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/12299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/comments?post=12299"}],"version-history":[{"count":1,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/12299\/revisions"}],"predecessor-version":[{"id":12300,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/12299\/revisions\/12300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media\/4747"}],"wp:attachment":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media?parent=12299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/categories?post=12299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/tags?post=12299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}