{"id":12242,"date":"2023-02-17T15:25:53","date_gmt":"2023-02-17T15:25:53","guid":{"rendered":"https:\/\/vila.es\/?p=12242"},"modified":"2023-02-17T15:25:53","modified_gmt":"2023-02-17T15:25:53","slug":"internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung","status":"publish","type":"post","link":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/","title":{"rendered":"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: justify;\">Auf internationaler Ebene beschlie\u00dfen viele Unternehmen, ihre Produkte im Ausland zu vermarkten. Zu diesem Zweck beschlie\u00dfen die Hersteller, eine vertragliche Beziehung mit der jeweiligen Vertriebsgesellschafteinzugehen, um die betreffenden Produkte in einem bestimmten Land (weiter-)zu verkaufen.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">In solchen F\u00e4llen schlie\u00dfen Hersteller und H\u00e4ndler in der Regel einen Vertriebsvertrag ab, um das Vertriebsverh\u00e4ltnis und ihre jeweiligen Rechte und Pflichten zu regeln. Allerdings kann es vorkommen, dass die Parteien den Inhalt des Vertriebsverh\u00e4ltnisses <strong>m\u00fcndlich<\/strong> vereinbaren, was bei m\u00f6glichen Verst\u00f6\u00dfen einer der Parteien oder bei <strong>Beendigung des Vertragsverh\u00e4ltnisses<\/strong> in der Zukunft zu Schwierigkeiten f\u00fchren kann.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">In F\u00e4llen, in denen kein schriftlicher Vertriebsvertrag zwischen den Parteien geschlossen wurde, ist zu pr\u00fcfen, ob es Unterlagen gibt, aus denen auf das Bestehen eines Vertriebsvertrags geschlossen werden kann. In diesem Zusammenhang ist darauf hinzuweisen, dass jeder Vertrag m\u00fcndlich oder schriftlich sein kann (wie aus Artikel 1.278 des Zivilgesetzbuches hervorgeht); im Falle eines m\u00fcndlichen Vertrages beruht er auf den Tatsachen und Handlungen der Parteien w\u00e4hrend der Dauer der Gesch\u00e4ftsbeziehung, und es ist daher ratsam, den Inhalt aller fr\u00fcheren Dokumente in Bezug auf die Vertriebsbeziehung oder Handlungen zu verfolgen, die es erm\u00f6glichen, die bestehenden Vereinbarungen zwischen den Parteien innerhalb der Gesch\u00e4ftsbeziehung zu bestimmen.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">In Anbetracht des Vorstehenden, f\u00fcr den Fall, dass eine oder beide Parteien die Beendigung des Vertriebsverh\u00e4ltnisses in Erw\u00e4gung ziehen, die Bestimmungen des einschl\u00e4gigen schriftlichen Vertriebsvertrags f\u00fcr die Zwecke der vertraglichen Beendigung und, in Ermangelung dessen, die Vereinbarungen zwischen den Parteien ber\u00fccksichtigt werden, die sich aus bereits bestehenden Dokumenten oder Akten ergeben. F\u00fcr den Fall, dass die Parteien die Beendigung des Vertriebsvertrags in Erw\u00e4gung ziehen und kein schriftlicher Vertrag vorliegt, sollte eine (vorzugsweise schriftliche) Aufhebungsvereinbarunggeschlossen werden, in der die Bedingungen f\u00fcr die Beendigung des Vertragsverh\u00e4ltnisses genau festgelegt werden, insbesondere in Bezug auf das Vorhandensein oder Nichtvorhandensein eines Kunden\u00fcbertragungsvertrags und die Bestimmung des anwendbaren Rechts und des zust\u00e4ndigen Gerichts f\u00fcr die Zwecke der Vertragsauslegung und der Beilegung etwaiger Streitigkeiten zwischen den Parteien.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">In einer solchen Situation, in der es keinen schriftlichen Vertriebsvertrag gibt, ist die Frage des <strong>anwendbaren Rechts<\/strong> von besonderem Interesse: Wenn es keinen schriftlichen Vertrag gibt, muss bestimmt werden, auf der Grundlage welcher Unterlagen oder Verfahren das anwendbare Recht zum Zwecke der Beendigung des Vertrags bestimmt werden kann. Und wenn es nicht m\u00f6glich ist, die Wahl des anwendbaren Rechts durch die Parteien auf diese Weise zu bestimmen, besteht die L\u00f6sung f\u00fcr eine solche Situation darin, das Recht als anwendbar zu bestimmen, das die Parteien f\u00fcr die Zwecke der Beendigung des Vertrags vereinbaren, und in Ermangelung einer Vereinbarung das Recht des Landes, in dem sich der gew\u00f6hnliche Aufenthalt des H\u00e4ndlers befindet, gem\u00e4\u00df den Bestimmungen von Artikel 4 Absatz 1 Buchstabe f der Verordnung (EG) Nr. 593\/2008 des Europ\u00e4ischen Parlaments und des Rates vom 17. Juni 2008 \u00fcber das auf vertragliche Schuldverh\u00e4ltnisse anzuwendende Recht (Rom I).<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Daraus l\u00e4sst sich schlie\u00dfen, dass das Vorhandensein eines <strong>schriftlichen<\/strong> Vertriebsvertrags seine Auslegung und die Bestimmung seines Geltungsbereichs erheblich erleichtert, da es in einem solchen Fall m\u00f6glich ist, die zwischen den Parteien getroffenen Vereinbarungen zu verschiedenen Aspekten (Vertriebsgebiet, \u00dcbertragung von Kunden, geistiges Eigentum, Vertragsk\u00fcndigung, anwendbares Recht, zust\u00e4ndige Gerichtsbarkeit usw.) zu \u00fcberpr\u00fcfen.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Die Unsicherheit, die durch m\u00fcndliche Vertr\u00e4ge entstehen kann, liegt auf der Hand, da jede Vertragspartei die M\u00f6glichkeit hat, das Vertragsverh\u00e4ltnis und die Vertragsbedingungen anders auszulegen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Albert Z\u00fa\u00f1iga Carulla<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Vil\u00e1 Abogados<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">F\u00fcr weitere Informationen wenden Sie sich bitte an:<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"mailto:va@vila.es\">va@vila.es<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">17. Februar 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf internationaler Ebene beschlie\u00dfen viele Unternehmen, ihre Produkte im Ausland zu vermarkten. Zu diesem Zweck beschlie\u00dfen die Hersteller, eine vertragliche Beziehung mit der jeweiligen Vertriebsgesellschafteinzugehen, um die betreffenden Produkte in einem bestimmten Land (weiter-)zu verkaufen. In solchen F\u00e4llen schlie\u00dfen Hersteller und H\u00e4ndler in der Regel einen Vertriebsvertrag ab, um das Vertriebsverh\u00e4ltnis und ihre jeweiligen Rechte  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":4676,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98,99],"tags":[],"class_list":["post-12242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handelsvertrage","category-vertriebs-und-vertretungsvertrage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG - Vil\u00e1 Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG - Vil\u00e1 Abogados\" \/>\n<meta property=\"og:description\" content=\"Auf internationaler Ebene beschlie\u00dfen viele Unternehmen, ihre Produkte im Ausland zu vermarkten. Zu diesem Zweck beschlie\u00dfen die Hersteller, eine vertragliche Beziehung mit der jeweiligen Vertriebsgesellschafteinzugehen, um die betreffenden Produkte in einem bestimmten Land (weiter-)zu verkaufen. In solchen F\u00e4llen schlie\u00dfen Hersteller und H\u00e4ndler in der Regel einen Vertriebsvertrag ab, um das Vertriebsverh\u00e4ltnis und ihre jeweiligen Rechte [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/\" \/>\n<meta property=\"og:site_name\" content=\"Vil\u00e1 Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-17T15:25:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vila.es\/wp-content\/uploads\/2015\/03\/contratacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"669\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vil\u00e1 Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vil\u00e1 Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/\"},\"author\":{\"name\":\"Vil\u00e1 Abogados\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"headline\":\"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG\",\"datePublished\":\"2023-02-17T15:25:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/\"},\"wordCount\":614,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/contratacion.jpg\",\"articleSection\":[\"Handelsvertr\u00e4ge\",\"Vertriebs und Vertretungsvertr\u00e4ge\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/\",\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/\",\"name\":\"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG - Vil\u00e1 Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/contratacion.jpg\",\"datePublished\":\"2023-02-17T15:25:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/contratacion.jpg\",\"contentUrl\":\"https:\\\/\\\/vila.es\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/contratacion.jpg\",\"width\":669,\"height\":272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vila.es\\\/de\\\/handelsvertrage\\\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vila.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vila.es\\\/en\\\/\",\"name\":\"Vil\u00e1 Abogados\",\"description\":\"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vila.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vila.es\\\/en\\\/#\\\/schema\\\/person\\\/1338568a83d16fbfd6073c8cc4834904\",\"name\":\"Vil\u00e1 Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g\",\"caption\":\"Vil\u00e1 Abogados\"},\"url\":\"https:\\\/\\\/vila.es\\\/de\\\/author\\\/vilaes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG - Vil\u00e1 Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/","og_locale":"de_DE","og_type":"article","og_title":"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG - Vil\u00e1 Abogados","og_description":"Auf internationaler Ebene beschlie\u00dfen viele Unternehmen, ihre Produkte im Ausland zu vermarkten. Zu diesem Zweck beschlie\u00dfen die Hersteller, eine vertragliche Beziehung mit der jeweiligen Vertriebsgesellschafteinzugehen, um die betreffenden Produkte in einem bestimmten Land (weiter-)zu verkaufen. In solchen F\u00e4llen schlie\u00dfen Hersteller und H\u00e4ndler in der Regel einen Vertriebsvertrag ab, um das Vertriebsverh\u00e4ltnis und ihre jeweiligen Rechte [...]","og_url":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/","og_site_name":"Vil\u00e1 Abogados","article_published_time":"2023-02-17T15:25:53+00:00","og_image":[{"width":669,"height":272,"url":"https:\/\/vila.es\/wp-content\/uploads\/2015\/03\/contratacion.jpg","type":"image\/jpeg"}],"author":"Vil\u00e1 Abogados","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Vil\u00e1 Abogados","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/#article","isPartOf":{"@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/"},"author":{"name":"Vil\u00e1 Abogados","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"headline":"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG","datePublished":"2023-02-17T15:25:53+00:00","mainEntityOfPage":{"@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/"},"wordCount":614,"commentCount":0,"image":{"@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2015\/03\/contratacion.jpg","articleSection":["Handelsvertr\u00e4ge","Vertriebs und Vertretungsvertr\u00e4ge"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/","url":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/","name":"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG - Vil\u00e1 Abogados","isPartOf":{"@id":"https:\/\/vila.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/#primaryimage"},"image":{"@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/#primaryimage"},"thumbnailUrl":"https:\/\/vila.es\/wp-content\/uploads\/2015\/03\/contratacion.jpg","datePublished":"2023-02-17T15:25:53+00:00","author":{"@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904"},"breadcrumb":{"@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/#primaryimage","url":"https:\/\/vila.es\/wp-content\/uploads\/2015\/03\/contratacion.jpg","contentUrl":"https:\/\/vila.es\/wp-content\/uploads\/2015\/03\/contratacion.jpg","width":669,"height":272},{"@type":"BreadcrumbList","@id":"https:\/\/vila.es\/de\/handelsvertrage\/internationale-vertriebsvertrag-muendliche-vertraege-und-moeglichkeiten-der-kuendigung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vila.es\/de\/"},{"@type":"ListItem","position":2,"name":"INTERNATIONALE VERTRIEBSVERTRAG: M\u00dcNDLICHE VERTR\u00c4GE UND M\u00d6GLICHKEITEN DER K\u00dcNDIGUNG"}]},{"@type":"WebSite","@id":"https:\/\/vila.es\/en\/#website","url":"https:\/\/vila.es\/en\/","name":"Vil\u00e1 Abogados","description":"Damos soporte jur\u00eddico a proyectos e iniciativas de negocio de empresas y de emprendedores extranjeros y nacionales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vila.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/vila.es\/en\/#\/schema\/person\/1338568a83d16fbfd6073c8cc4834904","name":"Vil\u00e1 Abogados","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80372a28ffd84e8b62261dc710c686e32c574bf8a1c71bfd6ebfba0f351a081b?s=96&d=mm&r=g","caption":"Vil\u00e1 Abogados"},"url":"https:\/\/vila.es\/de\/author\/vilaes\/"}]}},"_links":{"self":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/12242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/comments?post=12242"}],"version-history":[{"count":1,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/12242\/revisions"}],"predecessor-version":[{"id":12243,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/posts\/12242\/revisions\/12243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media\/4676"}],"wp:attachment":[{"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/media?parent=12242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/categories?post=12242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vila.es\/de\/wp-json\/wp\/v2\/tags?post=12242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}